{"id":10046,"date":"2018-03-02T18:28:17","date_gmt":"2018-03-02T16:28:17","guid":{"rendered":"http:\/\/blogs.deia.com\/anasagasti\/?p=10046"},"modified":"2018-03-02T18:29:29","modified_gmt":"2018-03-02T16:29:29","slug":"osakidetza-ante-las-declaraciones-de-roberto-seijo","status":"publish","type":"post","link":"http:\/\/blogs.deia.eus\/anasagasti\/2018\/03\/02\/osakidetza-ante-las-declaraciones-de-roberto-seijo\/","title":{"rendered":"Osakidetza ante las declaraciones de Roberto Seij\u00f3"},"content":{"rendered":"<p><strong>Viernes 2 de marzo de 2018<\/strong><\/p>\n<p><strong>Osakidetza ante las declaraciones de los sindicatos ERNE, ELA y SIPE <\/strong><\/p>\n<p><a href=\"http:\/\/blogs.deia.com\/anasagasti\/2018\/03\/02\/osakidetza-ante-las-declaraciones-de-roberto-seijo\/roberto-seijo\/\" rel=\"attachment wp-att-10047\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-10047\" src=\"http:\/\/blogs.deia.com\/anasagasti\/files\/2018\/03\/Roberto-Seij\u00f3.png\" alt=\"\" width=\"649\" height=\"298\" \/><\/a>En relaci\u00f3n a las declaraciones realizadas en el d\u00eda de ayer por los sindicatos de la Ertzaintza ERNE, ELA y SIPE respecto a la celebraci\u00f3n en marzo de la que han denominado \u201cSemana de la Salud\u201d y la amenaza colectiva de \u201ccoger bajas\u201d, desde el Departamento de Salud y Osakidetza queremos se\u00f1alar que:<\/p>\n<ul>\n<li><b>Lamentamos que se hayan realizado estas declaraciones ya que demuestran <strong>un absoluto menosprecio respecto de la profesionalidad de los m\u00e9dicos y m\u00e9dicas de Osakidetza.<\/strong><\/b><\/li>\n<li>En este sentido, recordar a estos sindicatos de la Ertzaintza que <strong>una baja m\u00e9dica no se coge seg\u00fan el criterio cada persona, <\/strong>sino que se prescribe por los m\u00e9dicos y m\u00e9dicas desde <strong>criterios objetivos de p\u00e9rdida de la salud<\/strong> que impidan el desempe\u00f1o laboral y sea necesario para el restablecimiento del proceso patol\u00f3gico de cada paciente.<\/li>\n<li style=\"list-style-type: none\"><\/li>\n<\/ul>\n<ul>\n<li><b>Banalizar el derecho a la incapacidad temporal de los trabajadores y trabajadoras, menospreciar la profesionalidad de los y las facultativos de Osakidetza y de los m\u00e9dicos y m\u00e9dicas de la inspecci\u00f3n m\u00e9dica del Departamento de Salud, adem\u00e1s de lamentable, <strong>supone una falta de respeto absoluto al sistema sanitario de Euskadi y a sus profesionales.<\/strong><\/b><\/li>\n<\/ul>\n<p><strong>A Casanova le parece que el Parlamento Vasco est\u00e1 a la derecha de la Audiencia Nacional.<\/strong><\/p>\n<p>Sigue coleando la decisi\u00f3n adoptada el pasado jueves por el Parlamento Vasco en la que se rechaza los homenajes a \u201cpersonas pertenecientes a ETA o que utilizaron o justificaron la violencia como medio para conseguir fines pol\u00edticos\u201d. El s\u00e1bado fue el parlamentario de EH Bildu, Iker Casanova, quien denunci\u00f3 que la C\u00e1mara de Gasteiz se coloc\u00f3 \u201ca la derecha de la Audiencia Nacional\u201d, al mostrar su \u201crechazo a los homenajes p\u00fablicos a personas que hayan pertenecido a ETA.<\/p>\n<p>Casanova se\u00f1al\u00f3 en Radio Euskadi que lo que pas\u00f3 el jueves en el Parlamento Vasco fue \u201cun paso atr\u00e1s en la normalizaci\u00f3n de este pa\u00eds, se hizo una criminalizaci\u00f3n de actitudes que no tienen que ser criminalizadas, que tienen que ser aceptadas con normalidad\u201d. Asimismo, agreg\u00f3 que \u201cel recibimiento a personas que han cumplido sus condenas es la expresi\u00f3n l\u00f3gica de alegr\u00eda de sus entornos sociales por ese acontecimiento, y ah\u00ed no existe exaltaci\u00f3n ni b\u00fasqueda de humillaci\u00f3n a nadie\u201d.<\/p>\n<p>Se define Casanova con estas consideraciones. Ya en un programa sabatino de radio se hab\u00eda opuesto a condenar a ETA. Este es pues el Comisario que tiene Sortu en el Parlamento, un tipo sin discurso \u00e9tico y que si ETA siguiera actuando lo explicar\u00eda en lo que \u00e9l acu\u00f1\u00f3 como \u201cel conflicto\u201d. Todo un sujeto.<\/p>\n<p>En este sentido, denunci\u00f3 que el Parlamento, con su decisi\u00f3n, se situ\u00f3 \u201ca la derecha\u201d de la Audiencia Nacional\u201d. \u201cDonde la Audiencia Nacional no ve homenaje ni humillaci\u00f3n, el Parlamento s\u00ed lo ve. Me parece bastante lamentable ser m\u00e1s papistas que el Papa, m\u00e1s derechistas que la Audiencia Nacional, y algunos partidos cayeron en la trampa de la campa\u00f1a de agitaci\u00f3n y propaganda del PP, que les ha salido bien\u201d, agreg\u00f3 Casanova, para quien este pronunciamiento de la C\u00e1mara vasca es \u201cun golpe\u201d a la Ponencia de Memoria y Paz. \u201cExiste consenso para abordar estos temas en un marco apropiado para afrontarlo de una manera constructiva y lo del jueves fue lo contrario, un exhibicionismo de las diferencias y una utilizaci\u00f3n pol\u00edtica de esta cuesti\u00f3n para ganar r\u00e9ditos por parte del PP\u201d, lament\u00f3.<\/p>\n<p>El portavoz parlamentario del PNV, Joseba Egibar, afirm\u00f3 que \u201cuna cosa es la bienvenida, recibir correctamente la familia a alguien que ha estado preso, y otra cosa es hacer una ostentaci\u00f3n, una exaltaci\u00f3n de todo ello\u201d. Desde el PSE, Jos\u00e9 Antonio Pastor se\u00f1al\u00f3 que homenajes a expresos de ETA, como el llevado a cabo en Andoain, pocos d\u00edas despu\u00e9s del aniversario del asesinato de Joseba Pagazaurtundua se convierten en \u201cdoblemente hirientes para los familiares de las v\u00edctimas\u201d.<\/p>\n<p>Por su lado, el parlamentario de Elkarrekin Podemos, Jon Hern\u00e1ndez, reconoci\u00f3 que todos los presos tienen derecho a que sus seres queridos les reciban en sus pueblos, pero advirti\u00f3 de que hay que tener en cuenta la visi\u00f3n de personas que, ante determinados actos, \u201cpuedan sentir dolor\u201d, y rechaz\u00f3 que la C\u00e1mara vasca se haya situado \u201ca la derecha\u201d de la Audiencia Nacional.<\/p>\n<p>Esto no lo entiende Iker Casanova, alguien que estuvo siete a\u00f1os en la c\u00e1rcel y que sigue sin abdicar de su creencia marxista leninista de que el fin justifica los medios. Y se jacta de ello.<\/p>\n<p>Yo, a un tipo de esta cala\u00f1a, le prohibir\u00eda ser parte de cualquier club democr\u00e1tico.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Viernes 2 de marzo de 2018 Osakidetza ante las declaraciones de los sindicatos ERNE, ELA y SIPE En relaci\u00f3n a las declaraciones realizadas en el d\u00eda de ayer por los sindicatos de la Ertzaintza ERNE, ELA y SIPE respecto a la celebraci\u00f3n en marzo de la que han denominado \u201cSemana de la Salud\u201d y la &hellip; <a href=\"http:\/\/blogs.deia.eus\/anasagasti\/2018\/03\/02\/osakidetza-ante-las-declaraciones-de-roberto-seijo\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Osakidetza ante las declaraciones de Roberto Seij\u00f3<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10046","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/posts\/10046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/comments?post=10046"}],"version-history":[{"count":3,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/posts\/10046\/revisions"}],"predecessor-version":[{"id":10050,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/posts\/10046\/revisions\/10050"}],"wp:attachment":[{"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/media?parent=10046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/categories?post=10046"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/tags?post=10046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}