{"id":10057,"date":"2018-03-04T21:05:20","date_gmt":"2018-03-04T19:05:20","guid":{"rendered":"http:\/\/blogs.deia.com\/anasagasti\/?p=10057"},"modified":"2018-03-04T21:05:20","modified_gmt":"2018-03-04T19:05:20","slug":"un-jesuita-como-dios-manda","status":"publish","type":"post","link":"http:\/\/blogs.deia.eus\/anasagasti\/2018\/03\/04\/un-jesuita-como-dios-manda\/","title":{"rendered":"Un Jesuita como Dios manda."},"content":{"rendered":"<p><strong>Domingo 4 de marzo de 2018<\/strong><\/p>\n<p><strong>Padre Sabino: El maestro de todos<\/strong><\/p>\n<p><a href=\"http:\/\/blogs.deia.com\/anasagasti\/2018\/03\/04\/un-jesuita-como-dios-manda\/287-18\/\" rel=\"attachment wp-att-10058\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-10058\" src=\"http:\/\/blogs.deia.com\/anasagasti\/files\/2018\/03\/287.18.jpg\" alt=\"\" width=\"384\" height=\"468\" srcset=\"http:\/\/blogs.deia.eus\/anasagasti\/files\/2018\/03\/287.18.jpg 650w, http:\/\/blogs.deia.eus\/anasagasti\/files\/2018\/03\/287.18-580x707.jpg 580w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/a>Trabaj\u00f3 incansablemente por la educaci\u00f3n en Guayana (Venezuela).<\/p>\n<p>El sacerdote Jesuita conocido por su alegr\u00eda y gran humanidad falleci\u00f3 a los 83 a\u00f1os.<\/p>\n<p>\u201cFui feliz. Y si hoy tengo que morir, en tus manos Dios, encomiendo mi esp\u00edritu\u201d.<\/p>\n<p>Estas fueron las \u00faltimas palabras que pronunci\u00f3 un hombre de coraz\u00f3n noble que dedic\u00f3 su vida al servicio desinteresado por los m\u00e1s pobres de la sociedad.<\/p>\n<p>Esa persona fue el s. j. Sabino Eizaguirre,\u00a0\u00a0quien naciendo en Euzkadi lleg\u00f3 a esta regi\u00f3n del mundo para dejar un legado de gran val\u00eda.<\/p>\n<p>Su vida fue un constante ejemplo de \u201ctrabajo sacrificado y muy valioso\u201d que muy pocas personas han realizado.<\/p>\n<p>A sus 83 a\u00f1os el padre Sabino falleci\u00f3 en Ciudad Guayana, lugar donde vivi\u00f3 m\u00e1s de 30 a\u00f1os y en el cual quiso pasar su \u00faltimo d\u00eda.<\/p>\n<p>El 20 de febrero se conoci\u00f3 la muerte del sacerdote de la orden jesuita, noticia que fue recibida con gran pesar por la feligres\u00eda guayanesa, el clero y la comunidad educativa.<\/p>\n<p>El \u201cpadrecito Sabino\u201d como todos lo conoc\u00edan parti\u00f3 a la casa de Dios tras sufrir un paro card\u00edaco.<\/p>\n<p><strong>Amor a Guayana<\/strong><\/p>\n<p>Fue un hombre con profundo amor hacia la tierra venezolana y especialmente a Guayana, ese fue uno de los rasgos caracter\u00edsticos que reconocieron sus amistades en \u00e9l.<\/p>\n<p>El padre jesuita fue fundador de m\u00e1s de doce centros educativos en la regi\u00f3n oriental del pa\u00eds y realiz\u00f3 innumerables trabajos con comunidades ind\u00edgenas de la zona.<\/p>\n<p>\u00d3scar Buroz, sacerdote de la Universidad Cat\u00f3lica Andr\u00e9s Bello \u2013 Guayana, (Ucab), comparti\u00f3 con Sabino desde el a\u00f1o 2004 y estuvo con \u00e9l hasta su \u00faltimo d\u00eda.<\/p>\n<p>Buroz relat\u00f3 que antes de su fallecimiento, el religioso llegaba de oficiar una celebraci\u00f3n eucar\u00edstica en la sede del Cicpc de Guayana.<\/p>\n<p>Al volver a su residencia en los anexos del Colegio Loyola, manifest\u00f3 no sentirse bien. Tras una revisi\u00f3n de su cardi\u00f3logo y de recibir sus medicamentos indic\u00f3 que ya el malestar hab\u00eda pasado. Sin embargo, al pasar varios minutos falleci\u00f3.<\/p>\n<p>Para el clero guayan\u00e9s, el padre Sabino fue un hombre que siempre ten\u00eda una sonrisa en su rostro y que siempre buscaba la fraternidad entre todos.<\/p>\n<p><strong>Ra\u00edces vascas <\/strong><\/p>\n<p>Un 31 de enero de 1936 naci\u00f3 Eizaguirre Irure en el pueblo de Aizarna, en Gipuzkoa (Euzkadi) .<\/p>\n<p>Era hijo de caser\u00edo modesto y por tanto de ra\u00edces humildes ya que su crianza fue en el campo, donde \u00e9l, sus hermanos y sus padres cultivaban\u00a0la tierra como se hac\u00eda en el pasado siglo.<\/p>\n<p>Su educaci\u00f3n de primaria y secundaria la recibi\u00f3 por parte de los jesuitas, y de all\u00ed naci\u00f3 sus deseos de sacerdocio. Con 19 a\u00f1os lleg\u00f3 a Venezuela al concluir su noviciado.<\/p>\n<p>En los a\u00f1os sesenta se traslad\u00f3 a Colombia donde estudi\u00f3 Humanidades y Filosof\u00eda en la Pontificia Universidad Javeriana.<\/p>\n<p>Despu\u00e9s regres\u00f3 a Euzkadi para ser ordenado sacerdote en 1966. Tras vivir uno de los momentos m\u00e1s significativos parti\u00f3 a \u201csu verdadero lugar\u201d, Venezuela, en 1970.<\/p>\n<p>Estuvo dos a\u00f1os como profesor en la Universidad Cat\u00f3lica Andr\u00e9s Bello (Ucab-Caracas) y luego inici\u00f3 la labor por la que ser\u00e1 muy recordado.<\/p>\n<p>Apasionado de la educaci\u00f3n y de ense\u00f1ar a los pueblos desprotegidos, el padre Sabino fund\u00f3 el Centro de Extensi\u00f3n Cultural Padre Francisco Wuytack y la Asociaci\u00f3n Civil Terepaima (Asocite).<\/p>\n<p><strong>Trabajo educativo<\/strong><\/p>\n<p>En la d\u00e9cada de los ochenta comenz\u00f3 su labor en los colegios de Fe y Alegr\u00eda. Fue pionero del Proyecto de Alfabetizaci\u00f3n Liberadora Abrebecha y director de varias zonas educativas como la de Centro-occidente y en Oriente.<\/p>\n<p>Estuvo en Cuman\u00e1, Gran Sabana, Pijiguaos, Puerto Ayacucho, Ciudad Guayana, Tucupita y otros lugares donde lleg\u00f3 su amor.<\/p>\n<p>Doris Toledo, exdirectora de la red Fe y Alegr\u00eda Puerto Ordaz, record\u00f3 que a sus 21 a\u00f1os lo conoci\u00f3 y vio en \u00e9l un alma \u201cmisionera que cre\u00eda en la gente\u201d.<\/p>\n<p>\u201cPara m\u00ed fue un formador de maestros y su legado es de humildad y sencillez\u201d, expres\u00f3 conmovida Toledo.<\/p>\n<p>Otra profesora que comparti\u00f3 largos a\u00f1os con Sabino, fue Yanitza Manrique, actual directora de Fe y Alegr\u00eda.<\/p>\n<p>\u201c\u00c9l fue un hombre que te ayudaba y te acompa\u00f1aba en todo, un gran gu\u00eda espiritual. Fue un fundador de varias escuelas que solo se llegan por v\u00eda fluvial en el r\u00edo Caura y eso dice mucho de su personalidad\u201d, apunt\u00f3 la educadora.<\/p>\n<p>\u201cAl final del camino me dir\u00e1n:<\/p>\n<p>\u2013 \u00bfHas vivido?, \u00bfhas amado?.<\/p>\n<p>Y yo, sin decir nada, abrir\u00e9 el coraz\u00f3n lleno de nombres\u201d.<\/p>\n<p>Estas\u00a0\u00a0palabras fueron pronunciada por Sabino en una de sus homil\u00edas en donde demostraba el gran afecto que sent\u00eda por las personas.<\/p>\n<p>La semana pasada la comunidad cat\u00f3lica de Guayana despidi\u00f3 al \u201cquerido Sabino\u201d en la capilla del Colegio Loyola.<\/p>\n<p>Monse\u00f1or Helizandro Ter\u00e1n, obispo de Ciudad Guayana, ofici\u00f3 una misa en homenaje a este \u201cgran servidor de Dios\u201d.<\/p>\n<p><strong>Amante de la oraci\u00f3n<\/strong><\/p>\n<p>Sus compa\u00f1eros de sacerdocio reconocieron que Sabino en su vida espiritual fue un \u201camante\u201d de la oraci\u00f3n y escucha a Dios. De all\u00ed su gran fuerza para el trabajo cotidiano.<\/p>\n<p>Y nosotros contentos de que un jesuita vasco, euskaldun, fuera tan querido por la gente m\u00e1s necesitada. Y seguramente, por aqu\u00ed sin enterarnos del gran labor hecho por este hombre de bien.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Domingo 4 de marzo de 2018 Padre Sabino: El maestro de todos Trabaj\u00f3 incansablemente por la educaci\u00f3n en Guayana (Venezuela). El sacerdote Jesuita conocido por su alegr\u00eda y gran humanidad falleci\u00f3 a los 83 a\u00f1os. \u201cFui feliz. Y si hoy tengo que morir, en tus manos Dios, encomiendo mi esp\u00edritu\u201d. Estas fueron las \u00faltimas palabras &hellip; <a href=\"http:\/\/blogs.deia.eus\/anasagasti\/2018\/03\/04\/un-jesuita-como-dios-manda\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Un Jesuita como Dios manda.<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10057","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/posts\/10057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/comments?post=10057"}],"version-history":[{"count":2,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/posts\/10057\/revisions"}],"predecessor-version":[{"id":10060,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/posts\/10057\/revisions\/10060"}],"wp:attachment":[{"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/media?parent=10057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/categories?post=10057"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/blogs.deia.eus\/anasagasti\/wp-json\/wp\/v2\/tags?post=10057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}