{"id":4143,"date":"2022-06-06T16:48:03","date_gmt":"2022-06-06T14:48:03","guid":{"rendered":"https:\/\/blogs.deia.eus\/agroviajeros\/?p=4143"},"modified":"2022-06-06T17:32:07","modified_gmt":"2022-06-06T15:32:07","slug":"entre-delfines-y-tejones","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/agroviajeros\/2022\/06\/06\/entre-delfines-y-tejones\/","title":{"rendered":"Entre delfines y tejones"},"content":{"rendered":"\n<p>Este mes de junio ha sucedido en Euskadi un hecho fuera de lo com\u00fan, se han avistado en la r\u00eda, entre Getxo y Portugalete, delfines nadando en manada. <a rel=\"noreferrer noopener\" href=\"https:\/\/www.deia.eus\/bizkaia\/2022\/06\/02\/delfines-ria-portugalete-getxo\/1225440.html\" target=\"_blank\">Tal y como lo recog\u00eda este peri\u00f3dico.<\/a><\/p>\n\n\n\n<p>Lo cierto y aunque nos pueda sorprender, el Cant\u00e1brico est\u00e1 repleto de este tipo de cet\u00e1ceos y otros muchos m\u00e1s. Y es que adentr\u00e1ndonos algunos kil\u00f3metros mar adentro, es habitual que estos simp\u00e1ticos mam\u00edferos marinos se acerquen a saludar hasta las embarcaciones. Son muy sociables y entra\u00f1ables, o por lo menos esa es la imagen que proyectan entre nosotros, porque es f\u00e1cil encontrar en las relucientes pieles de los delfines, marcas y cicatrices de peleas entre ellos.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Con delfines desde Bilbao\" width=\"660\" height=\"371\" src=\"https:\/\/www.youtube.com\/embed\/fN_f5qzFyEo?start=51&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Cuando se adentran a las playas y desembocaduras de los r\u00edos, es entonces cuando nos damos cuenta de lo cerca que vivimos unos de otros. Tan cerca y tan lejos. <strong>La inmensa mayor\u00eda de nosotros nos sorprendemos al saber que all\u00ed, entre el horizonte del mar y la costa, existe un gran familia de cet\u00e1ceos<\/strong>. No solo diferentes clases de delfines, tambi\u00e9n cachalotes, ballenas. Aunque debido al numero de ellos, los saltos y lo simp\u00e1ticos que son, los delfines son a los que m\u00e1s f\u00e1cil podremos avistar.<\/p>\n\n\n\n<p>Y aunque la visita de estos mam\u00edferos marinos nos alegre el d\u00eda, su acercamiento a la costa est\u00e1 llena de peligros; embarcaciones con las que chocar, varamientos,&#8230;<\/p>\n\n\n\n<p><strong>Verano, la mejor \u00e9poca para salir a la mar para ver cet\u00e1ceos<\/strong><\/p>\n\n\n\n<p>Esta estaci\u00f3n que comienza ahora, es la mejor \u00e9poca para echarse a la mar e ir en busca de cet\u00e1ceos. Los meses de verano suelen ser abundantes en anchoa y bonito que tanto gustan a estos animales marinos de gran tama\u00f1o, son \u201cla golosina de la mar\u201d como los denomina Gorka Ocio, bi\u00f3logo&nbsp;de <a href=\"http:\/\/verballenas.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Verballenas<\/a> (empresa que organiza salidas desde Santurtzi para avistar cet\u00e1ceos.)<\/p>\n\n\n\n<p><strong><mark class=\"has-inline-color has-dark-gray-color\">El Tej\u00f3n, a plena luz del d\u00eda en Donostia.<\/mark><\/strong><\/p>\n\n\n\n<p>Este must\u00e9lido de gran tama\u00f1o fue visto por la sociedad ornitol\u00f3gica Itsas Enara por la zona de Martutene en Gipuzkoa. Algo fuera de lo com\u00fan en esta especie, ya que estos escurridizos animales son de h\u00e1bitos nocturnos.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Azkonarra, gauez ibiltzeko ohitura duena, ez da erreza egunez ikustea. <a href=\"https:\/\/twitter.com\/ItsasEnara?ref_src=twsrc%5Etfw\">@ItsasEnara<\/a>-k Antondegin egindako grabazio zoragarri hau bidaltzen digu.<br><br>El tej\u00f3n, de h\u00e1bitos nocturnos, no es f\u00e1cil de ver de d\u00eda. <a href=\"https:\/\/twitter.com\/ItsasEnara?ref_src=twsrc%5Etfw\">@ItsasEnara<\/a> nos env\u00eda esta espectacular grabaci\u00f3n realizada en Antondegi. <a href=\"https:\/\/t.co\/502NvCiv8o\">pic.twitter.com\/502NvCiv8o<\/a><\/p>&mdash; Antondegi Berdea (@antondegiberdea) <a href=\"https:\/\/twitter.com\/antondegiberdea\/status\/1532293459851231243?ref_src=twsrc%5Etfw\">June 2, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>El tej\u00f3n tiene el tama\u00f1o de un perro y es reconocible por su rostro&nbsp;y hocico de color blanco y negro. Es originario de Europa. Le gusta vivir en el bosque de hoja caduca y arbustos y se alimenta de huevos, cereales, vegetales y carro\u00f1a. Aunque vive en sociedad, le gusta salir a cazar solo. Este entra\u00f1able animal desgraciadamente se encuentra en peligro de extinci\u00f3n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Este mes de junio ha sucedido en Euskadi un hecho fuera de lo com\u00fan, se han avistado en la r\u00eda, entre Getxo y Portugalete, delfines nadando en manada. Tal y como lo recog\u00eda este peri\u00f3dico. Lo cierto y aunque nos pueda sorprender, el Cant\u00e1brico est\u00e1 repleto de este tipo de cet\u00e1ceos y otros muchos m\u00e1s. &hellip; <a href=\"https:\/\/blogs.deia.eus\/agroviajeros\/2022\/06\/06\/entre-delfines-y-tejones\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Entre delfines y tejones<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":95,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1544],"tags":[377,329,169178,169174,18,33400,100080,169182,156112],"class_list":["post-4143","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-animales","tag-cantabrico","tag-cetaceos","tag-delfines","tag-euskadi","tag-getxo","tag-mamiferos","tag-marinos","tag-tejon"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/posts\/4143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/users\/95"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/comments?post=4143"}],"version-history":[{"count":9,"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/posts\/4143\/revisions"}],"predecessor-version":[{"id":4152,"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/posts\/4143\/revisions\/4152"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/media?parent=4143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/categories?post=4143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/agroviajeros\/wp-json\/wp\/v2\/tags?post=4143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}