{"id":10338,"date":"2017-09-15T07:33:26","date_gmt":"2017-09-15T06:33:26","guid":{"rendered":"http:\/\/blogs.deia.com\/bogandoporlared\/?p=10338"},"modified":"2017-09-14T08:36:48","modified_gmt":"2017-09-14T07:36:48","slug":"frivolizar-con-una-guerra-civil","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2017\/09\/15\/frivolizar-con-una-guerra-civil\/","title":{"rendered":"Frivolizar con una guerra civil"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2017\/09\/20170915_frivolizar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10339\" src=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2017\/09\/20170915_frivolizar.jpg\" alt=\"\" width=\"630\" height=\"483\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2017\/09\/20170915_frivolizar.jpg 630w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2017\/09\/20170915_frivolizar-580x445.jpg 580w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a><\/p>\n<p>La moda de no vacunar a los ni\u00f1os solo es entendible porque las pandemias est\u00e1n erradicadas entre quienes tienen tiempo para informarse en Internet buscando los argumentos m\u00e1s enrevesados. Del mismo modo, quien frivoliza con la guerra civil ha vivido muy lejos de enfrentamientos reales. Lo hace Julian Assange, el mago blanco de ese progresismo que no distingue la izquierda de la extrema derecha, cuando habla de Catalunya con absoluta irresponsabilidad.<\/p>\n<p><strong>Delito de \u201capolog\u00eda del refer\u00e9ndum\u201d<\/strong><\/p>\n<p>No es ninguna broma: una cuenta en Twitter del PP en Madrid argumentaba que el acto a favor del refer\u00e9ndum en Catalunya que iba a producirse en Madrid ha sido prohibido por hacer, precisamente, \u201capolog\u00eda de un refer\u00e9ndum\u201d como si esto fuera un delito. En serio: \u00bfno se escuchan cuando hablan ni se leen cuando escriben? \u00bfNo se dan cuenta del rid\u00edculo que hacen con ciertas afirmaciones como que la democracia tiene que impedir el derecho a decidir?<\/p>\n<p><strong>Hazte O\u00edr, de utilidad p\u00fablica (todav\u00eda)<\/strong><\/p>\n<p>Puede tener raz\u00f3n el ministro espa\u00f1ol de Interior cuando afirma que Hazte O\u00edr seguir\u00e1 siendo una asociaci\u00f3n de utilidad p\u00fablica porque est\u00e1 al corriente de todos los requerimientos administrativos y los procesos judiciales en los que est\u00e1 inmersa no se han resuelto. El problema, no obstante, es doble: \u00bfqui\u00e9n y por qu\u00e9 se declar\u00f3 de utilidad p\u00fablica a la extrema derecha? \u00bfNo hay suficientes motivos extraordinarios para tomar una decisi\u00f3n extraordinaria?<\/p>\n<p><strong>La realidad supera la ficci\u00f3n<\/strong><\/p>\n<p>Roberto Saviano est\u00e1 de promoci\u00f3n y su trabajo es llamar nuestra atenci\u00f3n para que hablemos de su \u00faltima novela, lo s\u00e9. Pero no es menos cierto que lo que cuenta en El Confidencial anima a que le mencionemos&#8230; Y a acercarnos a su trabajo. El autor, especializado en la mafia italiana, advierte de que su texto, sobre la crueldad de las nuevas generaciones de mafiosos, es superado por la realidad, en la que los m\u00e1s j\u00f3venes se muestran verdaderamente agresivos y sanguinarios.<\/p>\n<p><strong>La crisis en YouTube se estabiliza<\/strong><\/p>\n<p><a href=\"http:\/\/blogs.deia.com\/bogandoporlared\/2017\/06\/04\/inaceptable\/\" target=\"_blank\" rel=\"noopener\">Hace unos meses<\/a> les explic\u00e1bamos la crisis que estaban viviendo en YouTube algunos generadores de contenido, cuya zafiedad era al mismo tiempo reclamo para las audiencias j\u00f3venes y rechazo para las marcas que m\u00e1s dinero gastan en la plataforma como anunciantes. La mayor\u00eda de youtubers, leemos ahora en Magnet, han decidido generar contenido \u201cfamiliar\u201d para no perder dinero, y otros se resignan a pasar filtros de control con los que lo pierden.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La moda de no vacunar a los ni\u00f1os solo es entendible porque las pandemias est\u00e1n erradicadas entre quienes tienen tiempo para informarse en Internet buscando los argumentos m\u00e1s enrevesados. Del mismo modo, quien frivoliza con la guerra civil ha vivido muy lejos de enfrentamientos reales. Lo hace Julian Assange, el mago blanco de ese progresismo &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2017\/09\/15\/frivolizar-con-una-guerra-civil\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Frivolizar con una guerra civil<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[385,17735,62608,64778,99367,70527,103468,103402,370],"class_list":["post-10338","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-catalunya","tag-el-confidencial","tag-hazte-oir","tag-juan-ignacio-zoido","tag-julian-assange","tag-magnet","tag-roberto-saviano","tag-twiitter","tag-youtube"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/10338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=10338"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/10338\/revisions"}],"predecessor-version":[{"id":10340,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/10338\/revisions\/10340"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=10338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=10338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=10338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}