{"id":10700,"date":"2017-12-23T08:48:39","date_gmt":"2017-12-23T07:48:39","guid":{"rendered":"http:\/\/blogs.deia.com\/bogandoporlared\/?p=10700"},"modified":"2017-12-22T15:50:24","modified_gmt":"2017-12-22T14:50:24","slug":"ganaron-dos","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2017\/12\/23\/ganaron-dos\/","title":{"rendered":"Ganaron dos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10701\" src=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2017\/12\/20171223_puigdemont.jpg\" alt=\"\" width=\"1280\" height=\"911\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2017\/12\/20171223_puigdemont.jpg 1280w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2017\/12\/20171223_puigdemont-580x413.jpg 580w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2017\/12\/20171223_puigdemont-768x547.jpg 768w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2017\/12\/20171223_puigdemont-940x669.jpg 940w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>La batalla electoral la ha ganado Ciudadanos de un modo inapelable, pero en la guerra ha vencido Puigdemont haciendo m\u00edtines por v\u00eddeoconferencia y dej\u00e1ndose fotografiar viendo los encuentros del Girona en bares de Bruselas. No, no me gusta \u201cel Carles\u201d porque no he encontrado en \u00e9l rastro de ser un hombre de partido ni de valent\u00eda pol\u00edtica. Pero, vaya, es el vencedor del 21-D con todo el merecimiento. De hecho, es el \u00fanico cuya victoria no se va a desinflar.<\/p>\n<p><strong>Perdieron los dem\u00e1s, tambi\u00e9n el PDeCat<\/strong><\/p>\n<p>Los dem\u00e1s perdieron, algunos lo hicieron estrepitosamente y otros incluso subiendo esca\u00f1os como el PSC. Tambi\u00e9n perdi\u00f3 el PDeCat, que ha recibido una herencia desastrosa de aquella CiU hegem\u00f3nica. A Marta Pascal le urge cimentar porque convive con un presidente que no es de su confianza y que lastr\u00f3 la lista pero que, sin embargo, ha logrado capitalizar un proc\u00e9s inveros\u00edmil contra Espa\u00f1a, los pron\u00f3sticos y la l\u00f3gica tradicional de los partidos. ERC seguir\u00e1 pagando las Fantas.<\/p>\n<p><strong>No, Rivera, esos votos no son tuyos<\/strong><\/p>\n<p>Albert Rivera tiene que hacer una lectura fr\u00eda de los resultados, pero yo no contar\u00eda con ello. Los votos que recibi\u00f3 su partido no tienen que ver con el valor de su marca o el liderazgo de Arrimadas. El voto a Ciudadanos era el modo que encontraron cientos de miles de catalanes de hacer llegar su mensaje: que alguien pare este proc\u00e9s y arranque Catalunya. O Catalu\u00f1a. Dentro de unos meses Arrimadas estar\u00e1 en la oposici\u00f3n y en las municipales del 19 Ciudadanos no va a tocar poder.<\/p>\n<p><strong>Templado&#8230; M\u00e1s bien, fr\u00edo<\/strong><\/p>\n<p>No soy muy bueno haciendo predicciones y, una vez m\u00e1s, me he vuelto a equivocar: esperaba que Miquel Iceta reba\u00f1ara bastante m\u00e1s a Podemos. Pero al final no est\u00e1n contentos ni unos ni otros. Los dos esca\u00f1os m\u00e1s que gana el PSC no suponen nada: siguen en su suelo. Y Dom\u00e8nech y Colau han protagonizado el cap\u00edtulo catal\u00e1n del lento e irremediable descenso de Podemos. Es cierto que una campa\u00f1a polarizada vac\u00eda la zona templada, pero la izquierda espa\u00f1ola se ha enfriado totalmente en Catalunya.<\/p>\n<p><strong>Albiol tiene que marcharse<\/strong><\/p>\n<p>Las derrotas estrepitosas me han alegrado una semana que espero que me la compense Olentzero, finalmente. Los de la CUP siguen viviendo en una realidad paralela reclamando el valor de sus cuatro esca\u00f1os como si fueran los diez que ya no tienen. Y Albiol tiene que abandonar la pol\u00edtica. Alguien que lleva al PP hasta los tres asientos no puede echar las culpas a los dem\u00e1s y seguir adelante. No se trata de que d\u00e9 un paso atr\u00e1s: su carrera pol\u00edtica est\u00e1 liquidada.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La batalla electoral la ha ganado Ciudadanos de un modo inapelable, pero en la guerra ha vencido Puigdemont haciendo m\u00edtines por v\u00eddeoconferencia y dej\u00e1ndose fotografiar viendo los encuentros del Girona en bares de Bruselas. No, no me gusta \u201cel Carles\u201d porque no he encontrado en \u00e9l rastro de ser un hombre de partido ni de &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2017\/12\/23\/ganaron-dos\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Ganaron dos<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[55021,61335,83814,75723,103534,283,83939,64912],"class_list":["post-10700","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-ada-colau","tag-albert-rivera","tag-carles-puigdemont","tag-ines-arrimadas","tag-marta-pascal","tag-twitter","tag-xavier-domenech","tag-xavier-garcia-albiol"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/10700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=10700"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/10700\/revisions"}],"predecessor-version":[{"id":10702,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/10700\/revisions\/10702"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=10700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=10700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=10700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}