{"id":13504,"date":"2020-08-19T08:35:27","date_gmt":"2020-08-19T07:35:27","guid":{"rendered":"http:\/\/blogs.deia.eus\/bogandoporlared\/?p=13504"},"modified":"2020-08-19T08:35:29","modified_gmt":"2020-08-19T07:35:29","slug":"absolutamente-intolerable","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2020\/08\/19\/absolutamente-intolerable\/","title":{"rendered":"Absolutamente intolerable"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"598\" height=\"644\" src=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2020\/08\/20200819_intolerable.jpg\" alt=\"\" class=\"wp-image-13505\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2020\/08\/20200819_intolerable.jpg 598w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2020\/08\/20200819_intolerable-580x625.jpg 580w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/figure>\n\n\n\n<p>Nada justifica el acoso que est\u00e1n sufriendo Pablo Iglesias, Irene Montero y sus tres hijos peque\u00f1os, tanto en su residencia habitual como durante las vacaciones. Su salida de Asturias \u201cpor motivos de seguridad\u201d (esto es, porque hab\u00edan hecho p\u00fablica su situaci\u00f3n y hasta les esperaban al entrar a un bar) es absolutamente intolerable. Los dos pol\u00edticos tienen derecho a una vida privada y al descanso, como todos. Y los hooligans que participan y alimentan este acoso tienen que ser frenados en seco. Esto no es un escrache, que tambi\u00e9n me han resultado siempre criticables, esto es intolerable. Y punto.<\/p>\n\n\n\n<p><strong>Incre\u00edble<\/strong><br><\/p>\n\n\n\n<p>La capacidad de Juan Carlos I de hacer lo que le da la gana me parece incre\u00edble. Por supuesto, s\u00e9 que es fruto de d\u00e9cadas de impunidad, de pol\u00edticos, fuerzas de seguridad del Estado y de medios de comunicaci\u00f3n tap\u00e1ndole los esc\u00e1ndalos, pero sigo sin alcanzar a comprenderlo: \u00bfpor qu\u00e9? Y que no me vengan con que devolvi\u00f3 la democracia a Espa\u00f1a y luego la salv\u00f3 durante el golpe de Estado del 81, que visto lo visto y le\u00eddo lo le\u00eddo, cada d\u00eda cuela menos. Dos semanas despu\u00e9s sabemos que el Rey Em\u00e9rito est\u00e1 en Emiratos \u00c1rabes Unidos, una dictadura que ya ha sido generosa con \u00e9l antes. Se r\u00ede de su Espa\u00f1a.<\/p>\n\n\n\n<p><strong>Insalvable<\/strong><br><\/p>\n\n\n\n<p>Cada vez soy m\u00e1s esc\u00e9ptico en pol\u00edtica: no creo en grandes giros ni en grandes t\u00e1cticas a largo plazo. Y menos en la pol\u00edtica espa\u00f1ola, que se caracteriza por el aqu\u00ed y ahora, y por corregirse continuamente. As\u00ed que la decisi\u00f3n de Casado apartar a Cayetana \u00c1lvarez de Toledo de la portavoc\u00eda, en mi opini\u00f3n, no es m\u00e1s que eso: una correcci\u00f3n. No creo que suponga la apertura del PP para facilitar la vida al PSOE ni de lejos. Y despu\u00e9s de esta correcci\u00f3n, vendr\u00e1 otra, porque \u00c1lvarez de Toledo como diputada del PP pero relegada, mal; pero fuera de la bancada y con los brazos de Vox abiertos, puede ser todav\u00eda peor para Casado.<\/p>\n\n\n\n<p><strong>Imb\u00e9ciles<\/strong><br><\/p>\n\n\n\n<p>Ayer me sorprendi\u00f3 pasar por delante de la concentraci\u00f3n de negacionistas de la pandemia en Bilbao y encontrarme a m\u00e1s de 20 personas. Me sorprendi\u00f3 y me preocup\u00f3. Tambi\u00e9n vi a ertzainas identificando a esos ciudadanos que, sin mascarilla, creen que desaf\u00edan a alguien pero solo exhiben al tonto del pueblo. Espero que las multas lleguen y que no sean recurribles, y m\u00e1s en Madrid, donde convocantes y alborotadores como Miguel Bos\u00e9 han generado este efecto llamada para esc\u00e9pticos radicalmente equivocados. Est\u00e1 claro que del confinamiento no hemos salido mejores y que algunos han salido muy mal. Sin eufemismos.<\/p>\n\n\n\n<p><strong>Inesperado<\/strong><br><\/p>\n\n\n\n<p>El v\u00eddeo de la fiesta multitudinaria en una piscina de Wuhan que lleva un par de d\u00edas corriendo por las redes sociales me sorprendi\u00f3 tanto que, pese a encontrarlo en una fuente fiable como el Twitter de la agencia France-Presse, tuve que confirmar que era real, en Wuhan y actual. Y parece que s\u00ed lo es. La ciudad, epicentro de la pandemia mundial, ha recobrado la normalidad casi por completo y, aunque parezca una macrofiesta, algunos corresponsales en China han aclarado que el aforo s\u00ed estaba limitado. En cualquier caso, el mensaje es esperanzador: s\u00ed, se puede salir de la espiral de contagios\u2026 Pero con mano dura y conciencia social.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Nada justifica el acoso que est\u00e1n sufriendo Pablo Iglesias, Irene Montero y sus tres hijos peque\u00f1os, tanto en su residencia habitual como durante las vacaciones. Su salida de Asturias \u201cpor motivos de seguridad\u201d (esto es, porque hab\u00edan hecho p\u00fablica su situaci\u00f3n y hasta les esperaban al entrar a un bar) es absolutamente intolerable. Los dos &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2020\/08\/19\/absolutamente-intolerable\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Absolutamente intolerable<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[142761,157682,62584,160056,35076,64971,283],"class_list":["post-13504","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-cayetana-alvarez-de-toledo","tag-coronavirus","tag-france-presse","tag-jose-enrique-monrosi","tag-juan-carlos-i","tag-pablo-casado","tag-twitter"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/13504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=13504"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/13504\/revisions"}],"predecessor-version":[{"id":13506,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/13504\/revisions\/13506"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=13504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=13504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=13504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}