{"id":14079,"date":"2021-02-14T09:06:17","date_gmt":"2021-02-14T08:06:17","guid":{"rendered":"http:\/\/blogs.deia.eus\/bogandoporlared\/?p=14079"},"modified":"2021-02-12T15:13:46","modified_gmt":"2021-02-12T14:13:46","slug":"un-anno-perdido","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2021\/02\/14\/un-anno-perdido\/","title":{"rendered":"Un a\u00f1o perdido"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"445\" src=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2021\/02\/20210214_perdido-940x445.jpg\" alt=\"\" class=\"wp-image-14080\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2021\/02\/20210214_perdido-940x445.jpg 940w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2021\/02\/20210214_perdido-580x274.jpg 580w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2021\/02\/20210214_perdido-768x363.jpg 768w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2021\/02\/20210214_perdido.jpg 1600w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/figure>\n\n\n\n<p>El texto de Marta Garc\u00eda Aller en El Confidencial resulta muy sugerente\u2026 Aunque lo que sugiere es el tedio en el que todos estamos viviendo. O sobreviviendo. Llevamos como podemos el trabajo y la casa: la conciliaci\u00f3n hoy es solo un fundido pegado al jam\u00f3n en un sanjacobo ultracongelado. No hay viernes, no hay domingos, solo hay lunes. Vivimos desde hace un a\u00f1o en un bucle, y desde septiembre, en una especie de martes sin fin. Estamos jodidos, sin alicientes y agotados de que intenten manipularnos los pol\u00edticos que no toman decisiones sobre la pandemia. Y lo peor: no nos cuidamos entre nosotros.<\/p>\n\n\n\n<p><strong>No tenemos ganas para estas mierdas<\/strong><br><\/p>\n\n\n\n<p>En las elecciones catalanas que se celebran hoy tengo muy claro el partido al que habr\u00eda votado aunque no tiene ninguna posibilidad de ganar. Pero la dignidad de unos presos pol\u00edticos, de un pueblo entero y de cada una de las personas que lo forman es m\u00e1s importante que los juegos de liderazgos y pactos que se traen los favoritos. Dicho todo esto: me pongo de parte del PSC (al que no habr\u00eda elegido) en su denuncia a Alvise P\u00e9rez, que sigue haciendo el juego a la caverna desde Twitter incluso exhibiendo documentos falsos para sugerir que Illa se habr\u00eda vacunado. Estamos muy cansados para estas mierdas de fachas.<\/p>\n\n\n\n<p><strong>Dejad de intentar col\u00e1rnosla<\/strong><br><\/p>\n\n\n\n<p>Hace tiempo que decid\u00ed no compartir ni en mis redes sociales ni en esta columna ning\u00fan contenido de El Espa\u00f1ol. El digital de Pedro J. Ram\u00edrez es un gran aspersor de guano, y como tal hay que tratarlo. Pero esta noticia, sin duda, merece la pena que rompa mi norma sanitaria: \u201c\u2018Era m\u00e1s anticapitalista que anticomunista\u2019: la biograf\u00eda de Hitler que quiere cambiar la historia\u201d. Menudo moj\u00f3n, eh: por si no fuera todo suficientemente dif\u00edcil ahora nos quieren colocar que Hitler era malo pero no de la forma que lo ha fijado el consenso hist\u00f3rico. A quien nos trata como si fu\u00e9ramos tontos, igual que al facha, rechazo.<\/p>\n\n\n\n<p><strong>El gobierno m\u00e1s progresista de la historia<\/strong><br><\/p>\n\n\n\n<p>Otros que intentan infantilizarnos son los de Podemos con cada explicaci\u00f3n pol\u00edtica que ofrecen. Nos tratan como si no nos di\u00e9ramos cuenta de que la democracia ya exist\u00eda antes de que ellos decidieran formar su partido, y como si no supi\u00e9ramos que, por mucho que intenten separarse del gobierno son el gobierno tambi\u00e9n en titulares como este de P\u00fablico: \u201cEl Gobierno deja fuera de su pol\u00edtica de \u2018transparencia\u2019 cualquier dato sobre la huida del em\u00e9rito\u201d. Esto es lo que hace el gobierno m\u00e1s progresista de la historia de Espa\u00f1a, seg\u00fan sus aplaudidores, y el primero de coalici\u00f3n. <\/p>\n\n\n\n<p><strong>La huida hacia delante<\/strong><br><\/p>\n\n\n\n<p>La crisis econ\u00f3mica derivada de la pandemia del coronavirus est\u00e1 golpeando al f\u00fatbol y especialmente a los grandes clubes que han especulado con fichajes y sueldos, y que se ven ahora atados a sus contratos y con agujeros de millones que cada vez son m\u00e1s profundos. En su huida hacia delante, empresas como Real Madrid o Barcelona anhelan la millonada que les caer\u00eda de la Superliga europea. Y luego, \u00bfqu\u00e9? No tendr\u00edan nada que hacer contra clubes m\u00e1s saneados y un equipo de mitad de tabla de la Superliga es solo un equipo de mitad de tabla. Volver\u00edan a endeudarse y a empezar\u2026 Sin soluci\u00f3n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El texto de Marta Garc\u00eda Aller en El Confidencial resulta muy sugerente\u2026 Aunque lo que sugiere es el tedio en el que todos estamos viviendo. O sobreviviendo. Llevamos como podemos el trabajo y la casa: la conciliaci\u00f3n hoy es solo un fundido pegado al jam\u00f3n en un sanjacobo ultracongelado. No hay viernes, no hay domingos, &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2021\/02\/14\/un-anno-perdido\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Un a\u00f1o perdido<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[73512,145639,17735,64889,10799,35076,70365,48183,42846,4988],"class_list":["post-14079","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-adolf-hitler","tag-alvise-perez","tag-el-confidencial","tag-el-espanol","tag-fc-barcelona","tag-juan-carlos-i","tag-marta-garcia-aller","tag-pedro-j-ramirez","tag-publico","tag-real-madrid"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/14079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=14079"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/14079\/revisions"}],"predecessor-version":[{"id":14081,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/14079\/revisions\/14081"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=14079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=14079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=14079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}