{"id":16236,"date":"2023-02-23T08:28:00","date_gmt":"2023-02-23T07:28:00","guid":{"rendered":"https:\/\/blogs.deia.eus\/bogandoporlared\/?p=16236"},"modified":"2023-02-22T15:29:58","modified_gmt":"2023-02-22T14:29:58","slug":"no-sabe-lo-que-es-google","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2023\/02\/23\/no-sabe-lo-que-es-google\/","title":{"rendered":"<strong>No sabe lo que es Google<\/strong>"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/02\/20230223_google.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"649\" src=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/02\/20230223_google.jpg\" alt=\"\" class=\"wp-image-16237\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/02\/20230223_google.jpg 595w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/02\/20230223_google-580x633.jpg 580w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/a><\/figure>\n\n\n\n<p>No creo que Edmundo Bal llegue muy lejos. Lo siento por \u00e9l, pero si no conoce algo tan b\u00e1sico sus opciones, en pol\u00edtica y en lo que se proponga, nunca ser\u00e1n muchas. Me refiero a algo que pone en evidencia en uno de sus \u00faltimos tuits: no sabe usar Google. Lo que me preocupa es que en Ciudadanos nadie se lo haya chivado. \u00bfTan poco le quieren? \u00bfTal vez Bal siga usando Netscape? Lo que est\u00e1 claro es que no ha perdido 15 segundos para buscar respuestas a las preguntas que se hizo ayer en el Congreso: \u201c\u00bfC\u00f3mo se calcula el cupo? \u00bfQu\u00e9 servicios del Estado paga? \u00bfAlguien lo sabe?\u201d, y que suman m\u00e1s de medio mill\u00f3n de resultados en Google.<\/p>\n\n\n\n<p><strong>\u00bfD\u00f3nde estabas entonces?<\/strong><\/p>\n\n\n\n<p>\u00a1Qu\u00e9 gran canci\u00f3n es \u201cInsurrecci\u00f3n\u201d de El \u00daltimo de la Fila! Y qu\u00e9 gran estrofa esa que canturreamos ante alguna ca\u00edda del guindo: \u201c\u00bfD\u00f3nde estabas entonces cuando tanto te necesit\u00e9?\u201d. La que acaba de descubrir el fuego es Mertxe Aizpurua, que piensa que nadie ha hablado de la juventud en el Congreso antes que ella, antes de que a Bildu le haya dado por copiar al PNV hasta en la \u201cagenda vasca\u201d que ahora cita Matute. Aizpurua habl\u00f3 ayer de la juventud, que solo ha conocido una crisis en 2008. Entonces, yo tambi\u00e9n era joven y me pon\u00eda por mi cuenta, y me acuerdo perfectamente de d\u00f3nde estaba cada uno y una.<\/p>\n\n\n\n<p><strong>Dale, Pablo<\/strong><\/p>\n\n\n\n<p>Precisamente Bildu ha sido uno de los partidos invitados por Podemos en unas recientes jornadas sobre la invasi\u00f3n rusa sobre Ucrania en las que, significativamente, no hab\u00eda ninguna ni ning\u00fan refugiado ucraniano para explicarse. Ambos partidos son de los m\u00e1s importantes entre los que airean un falso dilema: o diplomacia o env\u00edo de armamento. La realidad, como siempre en sus casos, es otra: refuerzo a Ucrania para que se defienda mientras la diplomacia avanza. Pablo Iglesias va a\u00fan m\u00e1s lejos: apuesta \u201cpor entregar Crimea y Donb\u00e1s a Mosc\u00fa\u201d porque \u201ceso es lo m\u00e1s conveniente\u201d. Eso le afea en Twitter el periodista Luis de la Vega.<\/p>\n\n\n\n<p><strong>S\u00ed, es el mismo Putin<\/strong><\/p>\n\n\n\n<p>Pablo Iglesias justifica su argumento de entrega de territorios ucranianos para avanzar en la paz con que son regiones de mayor\u00eda rusoparlante. Como si la imposici\u00f3n de quien ocupa militarmente esas \u00e1reas, Rusia, no tuviese nada que ver. M\u00e1s all\u00e1 de la evidente tonter\u00eda, sigo sin entender c\u00f3mo alguien puede justificar a Putin sin cobrar por hacerlo. Un dictador de facto que reprime sin piedad la libertad de expresi\u00f3n en su pa\u00eds y que tiene una obsesi\u00f3n contra las personas homosexuales. Entonces, \u00bfes progresista entregar m\u00e1s territorios (en los que viven personas) a alguien con semejante visi\u00f3n del mundo?<\/p>\n\n\n\n<p><strong>No perdamos de vista los fundamentos<\/strong><\/p>\n\n\n\n<p>Siempre que tengo ocasi\u00f3n recupero los fundamentos de la comunicaci\u00f3n o el marketing: volviendo a ellos he deshecho nudos y he encontrado soluciones que parec\u00edan complejas. Del mismo modo, cuando me encuentro con una muestra de ese regreso a las ideas que no debemos perder de vista siempre la aprovecho. En este caso, la ha tuiteado Juan Antonio Giner a prop\u00f3sito de c\u00f3mo las cabeceras que tropiezan en la inmediatez: \u201cTodo esto sucede porque seguimos obsesionados con las \u2018breaking news\u2019 cuando, como dec\u00eda Gabo, \u2018lo importante no es qui\u00e9n da primero las noticias sino qui\u00e9n las da mejor\u2019\u201d. Pues eso.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No creo que Edmundo Bal llegue muy lejos. Lo siento por \u00e9l, pero si no conoce algo tan b\u00e1sico sus opciones, en pol\u00edtica y en lo que se proponga, nunca ser\u00e1n muchas. Me refiero a algo que pone en evidencia en uno de sus \u00faltimos tuits: no sabe usar Google. Lo que me preocupa es &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2023\/02\/23\/no-sabe-lo-que-es-google\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\"><strong>No sabe lo que es Google<\/strong><\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[162483,170042,53538,170043,157765,47772,25320,283,53508],"class_list":["post-16236","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-edmundo-bal","tag-el-ultimo-de-la-fila","tag-juan-antonio-giner","tag-luis-de-la-vega","tag-mertxe-aizpurua","tag-pablo-iglesias","tag-rusia","tag-twitter","tag-vladimir-putin"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/16236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=16236"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/16236\/revisions"}],"predecessor-version":[{"id":16238,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/16236\/revisions\/16238"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=16236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=16236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=16236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}