{"id":16470,"date":"2023-05-20T15:31:53","date_gmt":"2023-05-20T14:31:53","guid":{"rendered":"https:\/\/blogs.deia.eus\/bogandoporlared\/?p=16470"},"modified":"2023-05-22T15:35:06","modified_gmt":"2023-05-22T14:35:06","slug":"un-pp-ayusizado","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2023\/05\/20\/un-pp-ayusizado\/","title":{"rendered":"Un PP \u201cayusizado\u201d"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/05\/20230520_ayusizado.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"431\" src=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/05\/20230520_ayusizado-940x431.jpg\" alt=\"\" class=\"wp-image-16471\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/05\/20230520_ayusizado-940x431.jpg 940w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/05\/20230520_ayusizado-580x266.jpg 580w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/05\/20230520_ayusizado-768x352.jpg 768w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/05\/20230520_ayusizado-1536x704.jpg 1536w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/05\/20230520_ayusizado.jpg 1920w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/a><\/figure>\n\n\n\n<p>\u201cEl PP vasco prev\u00e9 que el mitin de la presidenta de la Comunidad de Madrid en el Palacio Euskalduna de la capital vizca\u00edna sea el que m\u00e1s simpatizantes atraiga de toda la campa\u00f1a, \u2018hay mucha ilusi\u00f3n, la gente tiene muchas ganas de verla\u2019\u201d. Mikel Segovia en El Independiente no puede resumir mejor lo que es el PP vasco hoy: una formaci\u00f3n reducida a su n\u00facleo duro despu\u00e9s de reabsorber a Ciudadanos, que era poco m\u00e1s que una familia en su ala derecha. Una formaci\u00f3n que abraza el ayusismo porque todo lo dem\u00e1s le ha fallado. Una formaci\u00f3n que solo aspira a conservar y activar al m\u00ednimo posible.<\/p>\n\n\n\n<p><strong>En la pol\u00edtica y en la vida<\/strong><\/p>\n\n\n\n<p>Las redes sociales digitales han empeorado la pol\u00edtica: los tuits se han convertido en la manera de comunicar de las y los representantes de la ciudadan\u00eda, y esta se ha hooliganizado, al menos, en parte, para defender y atacar a su partido y a los otros. \u00bfPara qu\u00e9? Pero en la vida no nos ha ido mucho mejor: perdemos nuestro valios\u00edsimo tiempo con gilipolleces pegadas unas a otras. Europa (que sirve para algo, insisto e insistir\u00e9) ya ha puesto el foco. Y el ministro espa\u00f1ol de Consumo, tambi\u00e9n: \u201cGarz\u00f3n carga contra los \u2018efectos nocivos\u2019 de TikTok, Meta o Twitter: provocan \u2018ansiedad\u2019 y \u2018depresi\u00f3n\u2019 en los j\u00f3venes\u201d (Rep\u00fablica). Y esto es innegable.<\/p>\n\n\n\n<p><strong>El peor problema, el propio Musk<\/strong><\/p>\n\n\n\n<p>Hablando de redes sociales: no hacen un mal resumen en Marketing Directo sobre \u201cel rosario de problemas que Elon Musk deja en herencia a la nueva CEO de Twitter\u201d, Linda Yaccarino. Uno de los m\u00e1s importantes, precisamente, lo puede solucionar la pol\u00edtica: la huida de anunciantes e ingresos podr\u00eda arreglarse revertiendo la norma de los anteriores propietarios de no permitir publicidad pol\u00edtica en la red. Otro problema es el control de gasto y el equilibrio con el personal necesario. Pero el principal es bregar con Elon Musk, que tiene toda la pinta de querer entrometerse en la gesti\u00f3n de la empresa por la que pag\u00f3 44.000 millones.<\/p>\n\n\n\n<p><strong>\u00bfHay que regularlo todo? S\u00ed<\/strong><\/p>\n\n\n\n<p>Hace tiempo que, por suerte, no o\u00edmos la milonga de la necesaria descentralizaci\u00f3n de Internet, como eufemismo de su desregulaci\u00f3n. Curiosamente, desde posiciones progresistas han alimentado durante a\u00f1os ideas ultraliberales. Es evidente, lo era entonces y espero que lo sea cada d\u00eda, m\u00e1s, que es necesaria una regulaci\u00f3n clara sobre todo lo que podemos hacer on-line. Porque mientras divagamos sobre lo que es progre y lo que es bobo, los malos avanzan: \u201c\u00bfQu\u00e9 hay detr\u00e1s de las aplicaciones que pagan por hacer encuestas? Recogen informaci\u00f3n personal que deber\u00edamos proteger y venden datos a terceros\u201d, avisan en Maldita.<\/p>\n\n\n\n<p><strong>A estos empoderamos<\/strong><\/p>\n\n\n\n<p>Tambi\u00e9n era evidente, evident\u00edsimo, que ampliar la grada de animaci\u00f3n en San Mam\u00e9s iba a servir para empoderar a los de siempre, a quienes consideran que la bandera para reclamar amnist\u00eda para los presos de ETA, la del Arrano Beltza con la que la izquierda abertzale quiso sustituir a la Ikurri\u00f1a o la que sirve para reconocer la ocupaci\u00f3n rusa del Donbass, son elementos de animaci\u00f3n. A quienes no van a animar cuando el equipo est\u00e1 ante su \u00faltima oportunidad. Esos son los que controlan la grada de animaci\u00f3n. No otros. Siempre lo fueron, pero muchos miraron para otro lado por la campa\u00f1a. Y no, no todas las campa\u00f1as son iguales.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u201cEl PP vasco prev\u00e9 que el mitin de la presidenta de la Comunidad de Madrid en el Palacio Euskalduna de la capital vizca\u00edna sea el que m\u00e1s simpatizantes atraiga de toda la campa\u00f1a, \u2018hay mucha ilusi\u00f3n, la gente tiene muchas ganas de verla\u2019\u201d. Mikel Segovia en El Independiente no puede resumir mejor lo que es &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2023\/05\/20\/un-pp-ayusizado\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Un PP \u201cayusizado\u201d<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[56888,5621,93253,36186,170147,91222,170146,140643,34853,77373,93442,391,156882,283],"class_list":["post-16470","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-alberto-garzon","tag-athletic-club-bilbao","tag-el-independiente","tag-elon-musk","tag-inigo-cabacas-herri-harmaila","tag-isabel-diaz-ayuso","tag-linda-yaccarino","tag-maldita","tag-marketing-directo","tag-meta","tag-mikel-segovia","tag-republica","tag-tiktok","tag-twitter"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/16470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=16470"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/16470\/revisions"}],"predecessor-version":[{"id":16472,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/16470\/revisions\/16472"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=16470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=16470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=16470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}