{"id":17002,"date":"2023-12-19T08:40:00","date_gmt":"2023-12-19T07:40:00","guid":{"rendered":"https:\/\/blogs.deia.eus\/bogandoporlared\/?p=17002"},"modified":"2023-12-18T14:42:00","modified_gmt":"2023-12-18T13:42:00","slug":"es-necesaria-la-huelga","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2023\/12\/19\/es-necesaria-la-huelga\/","title":{"rendered":"\u00bfEs necesaria la huelga?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/12\/20231218_huelga.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"450\" src=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/12\/20231218_huelga-940x450.jpg\" alt=\"\" class=\"wp-image-17003\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/12\/20231218_huelga-940x450.jpg 940w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/12\/20231218_huelga-580x278.jpg 580w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/12\/20231218_huelga-768x368.jpg 768w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/12\/20231218_huelga-1536x735.jpg 1536w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2023\/12\/20231218_huelga.jpg 1920w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><\/a><\/figure>\n\n\n\n<p>\u00bfEs necesaria la huelga de la funci\u00f3n p\u00fablica vasca? Me lo pregunto de la mejor manera que soy capaz de hacerlo: con dudas. Me lo pregunto como aut\u00f3nomo y me lo pregunto como persona usuaria de los servicios p\u00fablicos de la CAV: agradecido y apreciando el valor de la mayor\u00eda y con claras cr\u00edticas hacia una minor\u00eda del funcionariado, cuyas decisiones a veces son dif\u00edciles de comprender. \u00bfEl funcionariado vasco, en el que van a consolidarse 17.000 plazas antes de que termine 2024, sin contar las m\u00e1s de 3.000 \u00a0nuevas que van a crearse, necesita una huelga? \u00bfO la necesita quien quiere presentar al pa\u00eds como si estuviera paralizado?<\/p>\n\n\n\n<p><strong>Entonces, \u00bfno es una errata?<\/strong><\/p>\n\n\n\n<p>Vi el tuit el domingo, pocos minutos despu\u00e9s de que lo lanzaran, y no le di importancia: es una errata, de la an\u00e9cdota no se hace noticia. Lo vi de nuevo ayer por la ma\u00f1ana. Y he esperado, pacientemente, a que desapareciese, pero dos d\u00edas despu\u00e9s, a la hora en la que escribo la columna, Arnaldo Otegi sigue anunciando \u201cpoco trabajo\u201d como uno de sus argumentos para \u201csalir a ganar\u201d en las pr\u00f3ximas elecciones auton\u00f3micas. Una pena ese fallo (sigo pensando que lo es) que empa\u00f1a un acto de Bildu muy cuidado para dejar a todos los suyos y todas las suyas bien claro a qui\u00e9n tienen que votar en el proceso interno.<\/p>\n\n\n\n<p><strong>\u00bfLo peor para el pa\u00eds o para ella?<\/strong><\/p>\n\n\n\n<p>Malas y malos son las y los pol\u00edticos que confunden el pa\u00eds no ya con su partido, sino con ellas y ellos mismos: \u201cLa a\u00fan alcaldesa de Pamplona, a S\u00e1nchez: \u2018Eres lo peor que le ha pasado a este pa\u00eds, lo peor\u2019\u201d (El Independiente). Cristina Ibarrola lo dijo as\u00ed en la manifestaci\u00f3n que UPN, junto con PP y Vox, que ensucia todo lo que toca, convoc\u00f3 para denunciar lo que es evidente: un pacto entre Bildu, PSOE y GeroaBai para desplazar a una alcaldesa que, si bien hab\u00eda ganado las elecciones, no hab\u00eda conseguido un gobierno estable. Ibarrola y UPN llevan, por lo tanto, pecado y penitencia: parece que su tiempo ha pasado.<\/p>\n\n\n\n<p><strong>Casi todo empez\u00f3 con Podemos<\/strong><\/p>\n\n\n\n<p>No quito ni una pizca de importancia a c\u00f3mo el Caso Neurona fue utilizado por justicia y medios de comunicaci\u00f3n para desgastar a Podemos. Con esto claro podemos hablar de si al partido le debilitaron m\u00e1s los de fuera o los de dentro, pero la utilizaci\u00f3n es manifiesta. Y dejando esa utilizaci\u00f3n cristalina, debemos ponderar la relevancia del caso, y esto de Juan Carlos Monedero es, por lo menos, un poco exagerado: \u201c\u2018Neurona\u2019 es el segundo caso m\u00e1s importante de guerra sucia tras el terrorismo de Estado\u201d (P\u00fablico). Porque si algo conocemos en Euskadi es la utilizaci\u00f3n de la justicia, los medios y la pol\u00edtica para se\u00f1alar y desgastar.<\/p>\n\n\n\n<p><strong>Seguiremos disfrutando<\/strong><\/p>\n\n\n\n<p>Los octavos de final de la Champions League nos ofrecer\u00e1n una eliminatoria entre la Real Sociedad y el PSG. Una fiesta del f\u00fatbol vasco a doble vuelta que debemos disfrutar, pero no como un premio, sino como parte del camino que al equipo de Donostia le queda por recorrer. Su clasificaci\u00f3n como primera de grupo, por encima del Inter de Mil\u00e1n, ha sido impresionante. Pero lo mejor es su manera de competir en el torneo de clubes m\u00e1s importante del mundo. A ambos lados de la A-8 mordemos en el campo, y Alav\u00e9s y Osasuna siguen haciendo sus deberes. Solo falta el Eibar y seguir creciendo en el norte. El f\u00fatbol vasco mola.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00bfEs necesaria la huelga de la funci\u00f3n p\u00fablica vasca? Me lo pregunto de la mejor manera que soy capaz de hacerlo: con dudas. Me lo pregunto como aut\u00f3nomo y me lo pregunto como persona usuaria de los servicios p\u00fablicos de la CAV: agradecido y apreciando el valor de la mayor\u00eda y con claras cr\u00edticas hacia &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2023\/12\/19\/es-necesaria-la-huelga\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">\u00bfEs necesaria la huelga?<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[20662,170283,7236,170447,93253,61463,70392,42846,104,283],"class_list":["post-17002","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-arnaldo-otegi","tag-caso-neurona","tag-champions-league","tag-cristina-ibarrola","tag-el-independiente","tag-juan-carlos-monedero","tag-psg","tag-publico","tag-real-sociedad","tag-twitter"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/17002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=17002"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/17002\/revisions"}],"predecessor-version":[{"id":17004,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/17002\/revisions\/17004"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=17002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=17002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=17002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}