{"id":7182,"date":"2014-11-01T09:43:08","date_gmt":"2014-11-01T08:43:08","guid":{"rendered":"http:\/\/blogs.deia.com\/bogandoporlared\/?p=7182"},"modified":"2014-11-03T11:38:33","modified_gmt":"2014-11-03T10:38:33","slug":"reconociendo-a-euskadi-como-nacion","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2014\/11\/01\/reconociendo-a-euskadi-como-nacion\/","title":{"rendered":"Reconociendo a Euskadi como naci\u00f3n"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2014\/11\/20141101_nacion.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7183\" src=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2014\/11\/20141101_nacion.jpg\" alt=\"20141101_nacion\" width=\"548\" height=\"608\" \/><\/a> Adem\u00e1s del fruto econ\u00f3mico, el viaje a M\u00e9xico del lehendakari Urkullu y la consejera Tapia ya ha dado un beneficio pol\u00edtico concreto, que hemos podido ver, casi en directo, <a href=\"https:\/\/www.facebook.com\/urkullu\" target=\"_blank\">v\u00eda Facebook<\/a>: \u201cEl presidente del Senado mexicano, Luis Miguel Barbosa, ha mostrado todo su respeto al destino del pueblo vasco como Naci\u00f3n, y ha expresado su reconocimiento a la pluralidad del Estado espa\u00f1ol: \u2018Estamos de lado de que en las naciones se entienda el pluriculturalismo. Respetamos mucho el desarrollo que frente al mundo ustedes llevan a cabo para mantener una presencia aut\u00f3noma con un desarrollo hist\u00f3rico que creo que est\u00e1n construyendo de manera correcta\u2019, ha dicho\u201d.<\/p>\n<p><strong>El c\u00edrculo se cierra sobre Aguirre<\/strong><\/p>\n<p>Lo dejan claro, muy claro en \u2018Vozp\u00f3puli\u2019: \u201cLa \u2018trama P\u00fanica\u2019 encabezada por Francisco Granados no est\u00e1 siendo investigada \u00fanicamente por cobrar comisiones a empresas a cambio de adjudicaciones de contratos p\u00fablicos. Anticorrupci\u00f3n tambi\u00e9n quiere saber si sirvi\u00f3 para favorecer los intereses de familiares de altos cargos de la Comunidad de Madrid. Las denuncias de nepotismo salpican a Esperanza Aguirre, cuyas dos primas fueron contratadas en la Confederaci\u00f3n Empresarial Madrile\u00f1a, presidida por Arturo Fern\u00e1ndez a cambio de favores pol\u00edticos. Adem\u00e1s, las sombras de duda sobre la ex presidenta afectan a contratos p\u00fablicos, seg\u00fan fuentes de la causa\u201d.<\/p>\n<p><strong>El \u201ctop 10\u201d de pol\u00edticos imputados<\/strong><\/p>\n<p>Lo ha elaborado Moe de Triana y, por motivos de espacio, les trasladamos los 5 primeros: Rafael Blasco, ex Portavoz del PP en las Cortes Valencianas (casos G\u00fcrtel, Brugal y Cooperaci\u00f3n); Juan Antonio Roca, ex gerente de Urbanismo del Ayuntamiento de Marbella por el GIL (Operaci\u00f3n Malaya); Antonio Fern\u00e1ndez, exconsejero de empleo de la Junta de Andaluc\u00eda, del PSOE (caos de los ERE); Jaume Matas, ex presidente del Gobierno Balear, del PP (casos Palma Arena y N\u00f3os); Carlos Fabra, ex presidente de la Diputaci\u00f3n Provincial de Castell\u00f3n, del PP (5 delitos fiscales, tr\u00e1fico de influencias, 2 delitos de cohecho, fraude de 700 000 euros a Hacienda y se\u00f1alado por un testigo arrepentido como integrante de una red de pederastia).<\/p>\n<p><strong>El \u201cpeque\u00f1o Nicol\u00e1s\u201d, al final, har\u00e1 negocio<\/strong><\/p>\n<p>\u201cDos cadenas espa\u00f1olas ya le hayan tentado con ofertas millonarias, de seis cifras, para poder contar con sus servicios\u201d, leemos en \u2018Estrella Digital\u2019. Las \u201cdos cadenas\u201d que le han ofrecido dinero a Nicol\u00e1s G\u00f3mez podr\u00edan ser las que todos pensamos. Las seis cifras, espero que sean en pesetas, si no, la historia de este truh\u00e1n acabar\u00eda demasiado bien para su poca enjundia. \u201cIncluso le han ofrecido escribir un libro autobiogr\u00e1fico, pese a tener tan solo 20 a\u00f1os de edad\u201d, seguimos leyendo. Y creo que el tema se nos ha ido de las manos, porque lo que no pasa de an\u00e9cdota chusca y, por tal rese\u00f1able, no es un tema de millones.<\/p>\n<p><strong>El \u00e9xito en Twitter<\/strong><\/p>\n<p>La misma noticia la hemos encontrado en varios digitales, y se refiere al \u201cequipo de investigadores de la Universidad Polit\u00e9cnica de Madrid\u201d que ha analizado miles de conversaciones en Twitter aplicando \u201cun modelo computacional\u201d para llegar a la siguiente conclusi\u00f3n: los mensajes de los usuarios con muchos seguidores llegan m\u00e1s lejos, aunque tuiteen poco, que los usuarios con menos seguidores, aunque tuiteen mucho. Despu\u00e9s de esta perogrullada, dejo yo la m\u00eda generada con un sistema poco computacional: mis ojos. Para tener \u00e9xito en Twitter lo mejor es salir por la tele.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s del fruto econ\u00f3mico, el viaje a M\u00e9xico del lehendakari Urkullu y la consejera Tapia ya ha dado un beneficio pol\u00edtico concreto, que hemos podido ver, casi en directo, v\u00eda Facebook: \u201cEl presidente del Senado mexicano, Luis Miguel Barbosa, ha mostrado todo su respeto al destino del pueblo vasco como Naci\u00f3n, y ha expresado su &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2014\/11\/01\/reconociendo-a-euskadi-como-nacion\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Reconociendo a Euskadi como naci\u00f3n<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[62983,29858,40921,44670,64696,10685,42465,393,63076,72,46934,63088,63085,61426,63072,63087,283,63089,5627],"class_list":["post-7182","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-antonio-fernandez","tag-arturo-fernandez","tag-carlos-fabra","tag-el-boletin","tag-el-pequeno-nicolas","tag-esperanza-aguirre","tag-estrella-digital","tag-facebook","tag-francisco-granados","tag-inigo-urkullu","tag-jaume-matas","tag-juan-antonio-roca","tag-luis-miguel-barbosa","tag-moe-de-triana","tag-operacion-punica","tag-rafael-blasco","tag-twitter","tag-upm","tag-vozpopuli"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/7182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=7182"}],"version-history":[{"count":2,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/7182\/revisions"}],"predecessor-version":[{"id":7193,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/7182\/revisions\/7193"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=7182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=7182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=7182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}