{"id":8314,"date":"2015-10-29T08:46:14","date_gmt":"2015-10-29T07:46:14","guid":{"rendered":"http:\/\/blogs.deia.com\/bogandoporlared\/?p=8314"},"modified":"2015-10-27T09:48:27","modified_gmt":"2015-10-27T08:48:27","slug":"el-pp-boicotea-el-estatuto","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2015\/10\/29\/el-pp-boicotea-el-estatuto\/","title":{"rendered":"El PP boicotea el Estatuto"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2015\/10\/20151029_pp.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8315\" src=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2015\/10\/20151029_pp.jpg\" alt=\"20151029_pp\" width=\"693\" height=\"819\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2015\/10\/20151029_pp.jpg 693w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2015\/10\/20151029_pp-580x685.jpg 580w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a><\/p>\n<p>Agradecemos especialmente descubrir, de vez en cuando, que en Madrid tambi\u00e9n se dan cuenta de la actualidad vasca: \u201cEl gobierno del PP boicotea el Estatuto vasco. La norma que rige el autogobierno de Euskadi est\u00e1 congelada, 36 a\u00f1os despu\u00e9s de su aprobaci\u00f3n. Rajoy se niega a transferir 35 competencias pendientes y provoca el momento de mayor tensi\u00f3n con el ejecutivo de I\u00f1igo Urkullu\u201d (&#8216;P\u00fablico&#8217;). La normalidad pol\u00edtica igual permite que las cosas se vean como son.<\/p>\n<p><strong>El fino l\u00edmite de la \u201cimputaci\u00f3n\u201d<\/strong><\/p>\n<p>Sinceramente, no tengo opini\u00f3n sobre la decisi\u00f3n de Pedro S\u00e1nchez de nombrar a una \u201cimputada por corrupci\u00f3n\u201d como la segunda de abordo en el comit\u00e9 electoral del PSOE en Madrid. Lo que s\u00ed s\u00e9 es que quien juega con las imputaciones de los dem\u00e1s tiene que permitir que jueguen con las propias, y que tenemos que ser especialmente escrupuloso con se\u00f1alar a un imputado porque estamos se\u00f1alando a un inocente hasta que se demuestre lo contrario.<\/p>\n<p><strong>Los diputados m\u00e1s vagos<\/strong><\/p>\n<p>A lo que no hay que tener miedo es a se\u00f1alar a los representantes de la ciudadan\u00eda que en las c\u00e1maras optan por hacer lo menos que puedan, o que son colocados por los partidos para ahorrarse un sueldo en la estructura. En \u2018Voz\u00f3puli\u2019 se\u00f1alan a los 20 diputados y diputadas menos activos: todos del PP menos una socialista. Pero todos han cobrado el sueldo, algunos, incluso, con \u201cextras\u201d pese a su baj\u00edsima actividad. Toca ahora a la ciudadan\u00eda \u201cpremiar\u201d a sus partidos por permitirlo.<\/p>\n<p><strong>\u00bfInternet o televisi\u00f3n?<\/strong><\/p>\n<p>Quienes consideran que \u201cInternet\u201d es un bar\u00f3metro o incluso una palanca de cambio son reduccionistas incluso en su propia concepci\u00f3n de la herramienta: Twitter, Facebook en menor medida, alg\u00fan blog, un agregador, un par de foros y la p\u00e1gina de peticiones on-line (que no van a ning\u00fan lado) Change.org, son todo su universo. Para seguir, quienes se juegan las alubias, como los nuevos l\u00edderes (Rivera e Iglesias) saben que el cocido se reparte en televisi\u00f3n, y es ah\u00ed donde no quieren fallar, como recuerdan en \u2018Estrella Digital\u2019.<\/p>\n<p><strong>\u00bfImporta tanto la edad?<\/strong><\/p>\n<p>Tengo la pregunta pero no la respuesta. Y como yo, millones de estadounidenses y de personas que, fuera de ese pa\u00eds, seguimos la actualidad pol\u00edtica de los grandes l\u00edderes. Esta semana, Hillary Clinton ha cumplido 68 a\u00f1os sumergida en su propia campa\u00f1a para ser elegida la candidata dem\u00f3crata a la Casa Blanca, y su edad parece uno de los mayores impedimentos. Celebramos que no lo sea el hecho de que es mujer, pero nos disturba un poco esa duda sobre el peso de los a\u00f1os.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Agradecemos especialmente descubrir, de vez en cuando, que en Madrid tambi\u00e9n se dan cuenta de la actualidad vasca: \u201cEl gobierno del PP boicotea el Estatuto vasco. La norma que rige el autogobierno de Euskadi est\u00e1 congelada, 36 a\u00f1os despu\u00e9s de su aprobaci\u00f3n. Rajoy se niega a transferir 35 competencias pendientes y provoca el momento de &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2015\/10\/29\/el-pp-boicotea-el-estatuto\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">El PP boicotea el Estatuto<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[42465,56954,434,53649,42846,70314],"class_list":["post-8314","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-estrella-digital","tag-hillary-clinton","tag-la-informacion","tag-pedro-sanchez","tag-publico","tag-vozopuli"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/8314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=8314"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/8314\/revisions"}],"predecessor-version":[{"id":8316,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/8314\/revisions\/8316"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=8314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=8314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=8314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}