{"id":9108,"date":"2016-07-10T08:40:50","date_gmt":"2016-07-10T07:40:50","guid":{"rendered":"http:\/\/blogs.deia.com\/bogandoporlared\/?p=9108"},"modified":"2016-07-08T15:43:11","modified_gmt":"2016-07-08T14:43:11","slug":"no-no-son-negocios","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/bogandoporlared\/2016\/07\/10\/no-no-son-negocios\/","title":{"rendered":"No, no son negocios"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2016\/07\/20160710_negocios.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9110\" src=\"http:\/\/blogs.deia.com\/bogandoporlared\/files\/2016\/07\/20160710_negocios.jpg\" alt=\"20160710_negocios\" width=\"736\" height=\"795\" srcset=\"https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2016\/07\/20160710_negocios.jpg 736w, https:\/\/blogs.deia.eus\/bogandoporlared\/files\/2016\/07\/20160710_negocios-580x626.jpg 580w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/a><\/p>\n<p>Incluso ser\u00eda reprobable que dos diputados del PP se hubieran servido de su capacidad de influencia para lograr contratos y trabajo que les diera un sobresueldo de hasta tres millones euros. Pero lo de Pedro G\u00f3mez de la Serna y Gustavo de Ar\u00edstegui ha ido m\u00e1s all\u00e1: hubo pagos de m\u00e1s de 200.000 \u20ac a cambio de \u201cdocumentos de dos folios copiados directamente y literalmente de Wikipedia\u201d, e \u201chicieron trasvases de dinero de unas sociedades a otras, con el objetivo de defraudar a Hacienda\u201d (El Espa\u00f1ol).<\/p>\n<p><strong>Lo de Messi tampoco eran regates<\/strong><\/p>\n<p>En El Blog Salm\u00f3n explican en qu\u00e9 consist\u00eda el fraude por el que Leo Messi y su padre han sido condenados: b\u00e1sicamente, vendi\u00f3 sus derechos de imagen por 50.000 \u20ac a un grupo de empresas. Por esos 50.000 \u20ac s\u00ed que tribut\u00f3, y ese grupo de empresas era la pantalla de un complejo conglomerado que le permit\u00eda facturar grandes cantidades de dinero por su imagen, sin que \u00e9l viera, legalmente hablando, m\u00e1s que esos 50.000. El resto se quedaba en para\u00edsos fiscales y cuentas opacas detr\u00e1s de las que, al parecer, estaban Leo Messi y su padre.<\/p>\n<p><strong>Lo de Podemos s\u00ed es una crisis<\/strong><\/p>\n<p>Una de las caracter\u00edsticas de los nuevos partidos es que consumen los ciclos devor\u00e1ndolos. Lo que en el PSOE (partido cuyo espacio quer\u00eda ocupar Podemos) tard\u00f3 a\u00f1os en suceder: la lucha intestina que acab\u00f3 con el t\u00e1ndem Gonz\u00e1lez-Guerra, que tan buenos resultados obtuvo, se ha reproducido a una velocidad inusitada entre Iglesias y Errej\u00f3n. El segundo podr\u00eda seguir maniobrando internamente para acabar con el pacto con IU, y el primero notar\u00eda la presi\u00f3n del sector de Ada Colau, que apuesta por que I\u00f1igo Errej\u00f3n tome el mando, precisamente.<\/p>\n<p><strong>Tambi\u00e9n lo de Vueling<\/strong><\/p>\n<p>Ahora que parece que, por fin, se ha calmado el asunto, es un buen momento para resolver la duda: \u00bfqu\u00e9 ha pasado en Vueling para la compa\u00f1\u00eda haya vivido unos d\u00edas de caos semejante? En El Confidencial, entre otros, ofrecen una buena respuesta. \u00c1lex Cruz dise\u00f1\u00f3 un modelo de \u00e9xito: los aviones (y las tripulaciones) ten\u00edan que estar en el aire el mayor tiempo posible, exprimiendo el n\u00famero de viajes diario. Todo va bien (capitalizaci\u00f3n incluida) hasta que algo falla y el fr\u00e1gil montaje cae como una torre de naipes.<\/p>\n<p><strong>Zorionak, Pantallas Amigas!<\/strong><\/p>\n<p>El que s\u00ed es un modelo s\u00f3lido de \u00e9xito, con label vasco, es el de Pantallas Amigas, que esta semana recordaba en un tuit que se cumpl\u00edan siete a\u00f1os ya de su primer v\u00eddeo en YouTube. Siete a\u00f1os y casi cuatro millones de visualizaciones despu\u00e9s, Pantallas Amigas siguen siendo una referencia para trabajar en la prevenci\u00f3n de riesgos de los m\u00e1s j\u00f3venes ante una pantalla. Su primer mensaje sigue teniendo vigencia hoy: \u201cCuando una imagen tuya sale de tu tel\u00e9fono, pierdes el control sobre ella para siempre. \u00a1Puede acabar en Internet a la vista de todos o en los tel\u00e9fonos de gente que no querr\u00edas!\u201d.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Incluso ser\u00eda reprobable que dos diputados del PP se hubieran servido de su capacidad de influencia para lograr contratos y trabajo que les diera un sobresueldo de hasta tres millones euros. Pero lo de Pedro G\u00f3mez de la Serna y Gustavo de Ar\u00edstegui ha ido m\u00e1s all\u00e1: hubo pagos de m\u00e1s de 200.000 \u20ac a &hellip; <a href=\"https:\/\/blogs.deia.eus\/bogandoporlared\/2016\/07\/10\/no-no-son-negocios\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">No, no son negocios<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48013],"tags":[91151,46208,17735,48050,64889,82881,64780,27750,47772,87444,82880,283,5627,91152,34819,370],"class_list":["post-9108","post","type-post","status-publish","format-standard","hentry","category-los-apuntes","tag-alex-cruz","tag-el-blog-salmon","tag-el-confidencial","tag-el-confidencial-digital","tag-el-espanol","tag-gustavo-de-aristegui","tag-inigo-errejon","tag-leo-messi","tag-pablo-iglesias","tag-pantallas-amigas","tag-pedro-gomez-de-la-serna","tag-twitter","tag-vozpopuli","tag-vueling","tag-wikipedia","tag-youtube"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/9108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/comments?post=9108"}],"version-history":[{"count":1,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/9108\/revisions"}],"predecessor-version":[{"id":9111,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/posts\/9108\/revisions\/9111"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/media?parent=9108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/categories?post=9108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/bogandoporlared\/wp-json\/wp\/v2\/tags?post=9108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}