{"id":1384,"date":"2012-07-16T13:02:41","date_gmt":"2012-07-16T11:02:41","guid":{"rendered":"http:\/\/blogs.deia.com\/corrernoesdecobardes\/?p=1384"},"modified":"2012-07-16T13:02:41","modified_gmt":"2012-07-16T11:02:41","slug":"maraton-de-montana-galarleiz-primera-retirada","status":"publish","type":"post","link":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/2012\/07\/16\/maraton-de-montana-galarleiz-primera-retirada\/","title":{"rendered":"Maraton de monta\u00f1a Galarleiz. Primera Retirada."},"content":{"rendered":"<p>Me da la sensaci\u00f3n que los blogs se han convertido en las biograf\u00edas autorizadas. La gente cuenta lo que le interesa o como le interesa&#8230; y eso \u00a0no es correcto (bajo mi punto de vista). No creo que seamos un servicio p\u00fablico, pero si que hay que ser responsable con los dos o tres que te lean.\u00a0A qu\u00e9 viene todo esto? Bueno vamos poco a poco&#8230; a ver si se transmitir bien lo que quiero decir, que mi cerebro es m\u00e1s r\u00e1pido que mis piernas.<\/p>\n<p>El domingo me plant\u00e9 en la salida de la <em><strong>marat\u00f3n de monta\u00f1a Galarleiz<\/strong><\/em> con mi amigo Xabi, con la sana intenci\u00f3n de: Echar la ma\u00f1ana corriendo por el monte. 6 d\u00edas para recuperar de un Ironman? c\u00f3mo estaremos? Bueno ilusi\u00f3n ten\u00eda. Errores tambi\u00e9n. Durante la semana hab\u00eda entrenado poco (l\u00f3gicamente) pero me encontraba bien.<\/p>\n<p>Una marat\u00f3n como su propio nombre indica son 42km, pero en el monte son muchos m\u00e1s&#8230; Algo que subestim\u00e9. En condiciones normales no deber\u00eda tener problemas para correr una marat\u00f3n de monta\u00f1a (no es chuler\u00eda, pero con la carga de trabajo que llevaba era asumible). Pero esta claro que mi cuerpo aun no hab\u00eda interiorizado el Ironman.<\/p>\n<p>Sal\u00ed con br\u00edo, segundo error, estaba \u00e1gil, pero no ten\u00eda reserva. Hasta que me dur\u00f3 la gasolina iba muy agusto. Muy contento, sin ver lo que se me avecinaba. Tras el paso por el Zalama todo iba rodado, pero en las bajadas sufr\u00eda mucho. Ten\u00eda mucho desgaste muscular. Trato aguantar como puedo hasta que en un momento y sin avisar se me empiezan a encender luces rojas&#8230;<\/p>\n<p>El desgaste muscular hace que las bajadas las haga andando&#8230; y con el paso del tiempo todo haga andando. Estamos en la media marat\u00f3n, me mentalizo para sufrir y saber que esto solo va a ser un entreno para el <em><strong>reto Santurtzi a Bilbao del 28 de julio<\/strong><\/em>. Pero esto va a m\u00e1s, cuando me agacho a atarme las zapas veo que estoy mareado. As\u00ed que en avituallamiento previo al Kolitza hago acopio de casi todo lo que puedo. Subo el Kolitza solo por decir que lo he subido, pero una vez abajo y viendo un puesto de la cruz roja <em><strong>me retiro<\/strong><\/em>.<\/p>\n<figure id=\"attachment_1385\" aria-describedby=\"caption-attachment-1385\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blogs.deia.com\/corrernoesdecobardes\/files\/2012\/07\/galarleiz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1385\" src=\"http:\/\/blogs.deia.com\/corrernoesdecobardes\/files\/2012\/07\/galarleiz-300x177.jpg\" alt=\"\" width=\"300\" height=\"177\" srcset=\"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/files\/2012\/07\/galarleiz-300x177.jpg 300w, https:\/\/blogs.deia.eus\/corrernoesdecobardes\/files\/2012\/07\/galarleiz.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-1385\" class=\"wp-caption-text\">Recorrido<\/figcaption><\/figure>\n<p>Dec\u00eda lo de las biograf\u00edas autorizadas porque muchas veces la gente obvia esto: <em><strong>los malos ratos o las derrotas<\/strong><\/em>. Pero no me parece \u00e9tico. Las cosas hay que afrontarlas como vienen y puede que le sirvan a alguien. Es cierto que nunca me hab\u00eda retirado, pero no es menos cierto que tampoco tengo que demostrar nada a nadie. Y que lo primero es la salud. No iba y punto no hay que hacerse sangre ni vender que somos super-hombres, ni llevarlo todo a lo \u00e9pico&#8230; a buscar la haza\u00f1a m\u00e1s grande, el quien puede m\u00e1s&#8230; Cuando no se puede, no se puede. A parte que no me estaba divirtiendo y para lo que me pagan no me compensa si no disfruto.<\/p>\n<p>Pues es lo que hay, alguna vez ten\u00eda que ser la primera. Ayer estaba jodido de cabeza, de salud estaba bien. Aun as\u00ed fui a la cruz roja porque quer\u00eda saber porque me hab\u00eda dado ese baj\u00f3n. Al final no fue m\u00e1s que una<em><strong> bajada de az\u00facar<\/strong><\/em>, pero vamos lo tengo claro a la m\u00ednima me planto, el que esperase m\u00e1s de m\u00ed, pedirle disculpas. Porque esto tambi\u00e9n es el #metodosovietico.<\/p>\n<p>Un v\u00eddeo del Ironman de Roth 2012, mismo d\u00eda que Frankfurt pero sin lluvia:<\/p>\n<iframe loading=\"lazy\" title=\"Challenge Roth 2012 - Spannende ETU Europameisterschaften im Langdistanz Triathlon\" width=\"660\" height=\"371\" src=\"https:\/\/www.youtube.com\/embed\/Xse1oJkfKJg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<p>Un saludo<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me da la sensaci\u00f3n que los blogs se han convertido en las biograf\u00edas autorizadas. La gente cuenta lo que le interesa o como le interesa&#8230; y eso \u00a0no es correcto (bajo mi punto de vista). No creo que seamos un servicio p\u00fablico, pero si que hay que ser responsable con los dos o tres que &hellip; <a href=\"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/2012\/07\/16\/maraton-de-montana-galarleiz-primera-retirada\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Maraton de monta\u00f1a Galarleiz. Primera Retirada.<\/span><\/a><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":52,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1167,1170],"class_list":["post-1384","post","type-post","status-publish","format-standard","hentry","category-competiciones","tag-metodosovietico","tag-galarleiz"],"_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/posts\/1384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/comments?post=1384"}],"version-history":[{"count":6,"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/posts\/1384\/revisions"}],"predecessor-version":[{"id":1392,"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/posts\/1384\/revisions\/1392"}],"wp:attachment":[{"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/media?parent=1384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/categories?post=1384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.deia.eus\/corrernoesdecobardes\/wp-json\/wp\/v2\/tags?post=1384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}