{"id":2663,"date":"2017-04-23T17:29:16","date_gmt":"2017-04-23T15:29:16","guid":{"rendered":"http:\/\/blogs.deia.com\/el-espacio-interior\/files\/2017\/04\/IMG_8640.jpg"},"modified":"2017-04-23T17:29:16","modified_gmt":"2017-04-23T15:29:16","slug":"img-8640","status":"inherit","type":"attachment","link":"https:\/\/blogs.deia.eus\/el-espacio-interior\/img-8640\/","title":{"rendered":"IMG_8640"},"author":111,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-2663","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"300\" src=\"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640-235x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640-235x300.jpg 235w, https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640.jpg 640w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->"},"caption":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":816,"file":"2017\/04\/IMG_8640.jpg","sizes":{"thumbnail":{"file":"IMG_8640-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640-150x150.jpg"},"medium":{"file":"IMG_8640-235x300.jpg","width":235,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640-235x300.jpg"},"post-thumbnail":{"file":"IMG_8640-640x510.jpg","width":640,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640-640x510.jpg"},"full":{"file":"IMG_8640.jpg","width":640,"height":816,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8640.jpg","_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/media\/2663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/comments?post=2663"}]}}