{"id":2673,"date":"2017-04-23T17:29:37","date_gmt":"2017-04-23T15:29:37","guid":{"rendered":"http:\/\/blogs.deia.com\/el-espacio-interior\/files\/2017\/04\/IMG_8665.jpg"},"modified":"2017-04-23T17:29:37","modified_gmt":"2017-04-23T15:29:37","slug":"img-8665","status":"inherit","type":"attachment","link":"https:\/\/blogs.deia.eus\/el-espacio-interior\/img-8665\/","title":{"rendered":"IMG_8665"},"author":111,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-2673","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665-250x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665-250x300.jpg 250w, https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665.jpg 640w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->"},"caption":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":768,"file":"2017\/04\/IMG_8665.jpg","sizes":{"thumbnail":{"file":"IMG_8665-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665-150x150.jpg"},"medium":{"file":"IMG_8665-250x300.jpg","width":250,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665-250x300.jpg"},"post-thumbnail":{"file":"IMG_8665-640x510.jpg","width":640,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665-640x510.jpg"},"full":{"file":"IMG_8665.jpg","width":640,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/blogs.deia.eus\/el-espacio-interior\/files\/2017\/04\/IMG_8665.jpg","_links":{"self":[{"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/media\/2673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.deia.eus\/el-espacio-interior\/wp-json\/wp\/v2\/comments?post=2673"}]}}